{"id":40219,"date":"2022-09-14T02:03:41","date_gmt":"2022-09-14T00:03:41","guid":{"rendered":"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17.jpg"},"modified":"2022-09-14T02:03:41","modified_gmt":"2022-09-14T00:03:41","slug":"img-zyczenia-wielkanocne-6","status":"inherit","type":"attachment","link":"https:\/\/www.pern.pl\/en\/img-zyczenia-wielkanocne-6\/","title":{"rendered":"IMG &#8211; \u017byczenia Wielkanocne"},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-40219","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IMG - \u017byczenia Wielkanocne - PERN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pern.pl\/en\/img-zyczenia-wielkanocne-6\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMG - \u017byczenia Wielkanocne - PERN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pern.pl\/en\/img-zyczenia-wielkanocne-6\/\" \/>\n<meta property=\"og:site_name\" content=\"PERN\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pern.pl\\\/en\\\/img-zyczenia-wielkanocne-6\\\/\",\"url\":\"https:\\\/\\\/www.pern.pl\\\/en\\\/img-zyczenia-wielkanocne-6\\\/\",\"name\":\"IMG - \u017byczenia Wielkanocne - PERN\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pern.pl\\\/en\\\/#website\"},\"datePublished\":\"2022-09-14T00:03:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pern.pl\\\/en\\\/img-zyczenia-wielkanocne-6\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pern.pl\\\/en\\\/img-zyczenia-wielkanocne-6\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pern.pl\\\/en\\\/img-zyczenia-wielkanocne-6\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.pern.pl\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IMG &#8211; \u017byczenia Wielkanocne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pern.pl\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.pern.pl\\\/en\\\/\",\"name\":\"PERN\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pern.pl\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMG - \u017byczenia Wielkanocne - PERN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pern.pl\/en\/img-zyczenia-wielkanocne-6\/","og_locale":"en_US","og_type":"article","og_title":"IMG - \u017byczenia Wielkanocne - PERN","og_url":"https:\/\/www.pern.pl\/en\/img-zyczenia-wielkanocne-6\/","og_site_name":"PERN","og_image":[{"width":1280,"height":640,"url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pern.pl\/en\/img-zyczenia-wielkanocne-6\/","url":"https:\/\/www.pern.pl\/en\/img-zyczenia-wielkanocne-6\/","name":"IMG - \u017byczenia Wielkanocne - PERN","isPartOf":{"@id":"https:\/\/www.pern.pl\/en\/#website"},"datePublished":"2022-09-14T00:03:41+00:00","breadcrumb":{"@id":"https:\/\/www.pern.pl\/en\/img-zyczenia-wielkanocne-6\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pern.pl\/en\/img-zyczenia-wielkanocne-6\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pern.pl\/en\/img-zyczenia-wielkanocne-6\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pern.pl\/en\/"},{"@type":"ListItem","position":2,"name":"IMG &#8211; \u017byczenia Wielkanocne"}]},{"@type":"WebSite","@id":"https:\/\/www.pern.pl\/en\/#website","url":"https:\/\/www.pern.pl\/en\/","name":"PERN","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pern.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17-300x150.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17-300x150.jpg 300w, https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17-1024x512.jpg 1024w, https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17-768x384.jpg 768w, https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17-1200x600.jpg 1200w, https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17.jpg 1280w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1280,"height":640,"file":"2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17.jpg","filesize":145318,"sizes":{"medium":{"file":"a0dda12eceaad509d0beb179f31e4e45-17-300x150.jpg","width":300,"height":150,"filesize":7725,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17-300x150.jpg"},"large":{"file":"a0dda12eceaad509d0beb179f31e4e45-17-1024x512.jpg","width":1024,"height":512,"filesize":59234,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17-1024x512.jpg"},"thumbnail":{"file":"a0dda12eceaad509d0beb179f31e4e45-17-150x150.jpg","width":150,"height":150,"filesize":4866,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17-150x150.jpg"},"medium_large":{"file":"a0dda12eceaad509d0beb179f31e4e45-17-768x384.jpg","width":768,"height":384,"filesize":37850,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17-768x384.jpg"},"post-thumbnail":{"file":"a0dda12eceaad509d0beb179f31e4e45-17-1200x600.jpg","width":1200,"height":600,"filesize":76512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17-1200x600.jpg"},"full":{"file":"a0dda12eceaad509d0beb179f31e4e45-17.jpg","width":1280,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2020\/04\/a0dda12eceaad509d0beb179f31e4e45-17.jpg","filename":"a0dda12eceaad509d0beb179f31e4e45-17.jpg","filesize":145318,"_links":{"self":[{"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/media\/40219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/types\/attachment"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/comments?post=40219"}]}}