{"id":37080,"date":"2022-09-09T17:51:38","date_gmt":"2022-09-09T15:51:38","guid":{"rendered":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10.jpg"},"modified":"2022-09-09T17:51:38","modified_gmt":"2022-09-09T15:51:38","slug":"img-pern-stawia-na-ekologie-9-2","status":"inherit","type":"attachment","link":"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/","title":{"rendered":"IMG &#8211; PERN stawia na ekologi\u0119"},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-37080","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IMG - PERN stawia na ekologi\u0119 - PERN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMG - PERN stawia na ekologi\u0119 - PERN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/\" \/>\n<meta property=\"og:site_name\" content=\"PERN\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/\",\"url\":\"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/\",\"name\":\"IMG - PERN stawia na ekologi\u0119 - PERN\",\"isPartOf\":{\"@id\":\"https:\/\/www.pern.pl\/en\/#website\"},\"datePublished\":\"2022-09-09T15:51:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pern.pl\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IMG &#8211; PERN stawia na ekologi\u0119\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pern.pl\/en\/#website\",\"url\":\"https:\/\/www.pern.pl\/en\/\",\"name\":\"PERN\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pern.pl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMG - PERN stawia na ekologi\u0119 - PERN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/","og_locale":"en_US","og_type":"article","og_title":"IMG - PERN stawia na ekologi\u0119 - PERN","og_url":"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/","og_site_name":"PERN","og_image":[{"width":2560,"height":1280,"url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/","url":"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/","name":"IMG - PERN stawia na ekologi\u0119 - PERN","isPartOf":{"@id":"https:\/\/www.pern.pl\/en\/#website"},"datePublished":"2022-09-09T15:51:38+00:00","breadcrumb":{"@id":"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pern.pl\/en\/img-pern-stawia-na-ekologie-9-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pern.pl\/en\/"},{"@type":"ListItem","position":2,"name":"IMG &#8211; PERN stawia na ekologi\u0119"}]},{"@type":"WebSite","@id":"https:\/\/www.pern.pl\/en\/#website","url":"https:\/\/www.pern.pl\/en\/","name":"PERN","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pern.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-scaled.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"150\" src=\"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-300x150.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-300x150.jpg 300w, https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-1024x512.jpg 1024w, https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-768x384.jpg 768w, https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-1536x768.jpg 1536w, https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-2048x1024.jpg 2048w, https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-1200x600.jpg 1200w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":2560,"height":1280,"file":"2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-scaled.jpg","filesize":167462,"sizes":{"medium":{"file":"38a39698ba53ab291dc0b1e725f894d9-10-300x150.jpg","width":300,"height":150,"filesize":7613,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-300x150.jpg"},"large":{"file":"38a39698ba53ab291dc0b1e725f894d9-10-1024x512.jpg","width":1024,"height":512,"filesize":41718,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-1024x512.jpg"},"thumbnail":{"file":"38a39698ba53ab291dc0b1e725f894d9-10-150x150.jpg","width":150,"height":150,"filesize":4164,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-150x150.jpg"},"medium_large":{"file":"38a39698ba53ab291dc0b1e725f894d9-10-768x384.jpg","width":768,"height":384,"filesize":27525,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-768x384.jpg"},"1536x1536":{"file":"38a39698ba53ab291dc0b1e725f894d9-10-1536x768.jpg","width":1536,"height":768,"filesize":76560,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-1536x768.jpg"},"2048x2048":{"file":"38a39698ba53ab291dc0b1e725f894d9-10-2048x1024.jpg","width":2048,"height":1024,"filesize":116974,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-2048x1024.jpg"},"post-thumbnail":{"file":"38a39698ba53ab291dc0b1e725f894d9-10-1200x600.jpg","width":1200,"height":600,"filesize":52573,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-1200x600.jpg"},"full":{"file":"38a39698ba53ab291dc0b1e725f894d9-10-scaled.jpg","width":2560,"height":1280,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-scaled.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]},"original_image":"38a39698ba53ab291dc0b1e725f894d9-10.jpg"},"post":null,"source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2021\/08\/38a39698ba53ab291dc0b1e725f894d9-10-scaled.jpg","_links":{"self":[{"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/media\/37080","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/types\/attachment"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/comments?post=37080"}]}}