{"id":28469,"date":"2022-09-05T13:20:47","date_gmt":"2022-09-05T11:20:47","guid":{"rendered":"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18.jpg"},"modified":"2022-09-05T13:20:47","modified_gmt":"2022-09-05T11:20:47","slug":"img-centrala-pern-napedzana-energia-sloneczna-17-2","status":"inherit","type":"attachment","link":"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/","title":{"rendered":"IMG &#8211; Centrala PERN nap\u0119dzana energi\u0105 s\u0142oneczn\u0105"},"author":0,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false},"class_list":["post-28469","attachment","type-attachment","status-inherit","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>IMG - Centrala PERN nap\u0119dzana energi\u0105 s\u0142oneczn\u0105 - PERN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"IMG - Centrala PERN nap\u0119dzana energi\u0105 s\u0142oneczn\u0105 - PERN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/\" \/>\n<meta property=\"og:site_name\" content=\"PERN\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/\",\"url\":\"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/\",\"name\":\"IMG - Centrala PERN nap\u0119dzana energi\u0105 s\u0142oneczn\u0105 - PERN\",\"isPartOf\":{\"@id\":\"https:\/\/www.pern.pl\/en\/#website\"},\"datePublished\":\"2022-09-05T11:20:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.pern.pl\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IMG &#8211; Centrala PERN nap\u0119dzana energi\u0105 s\u0142oneczn\u0105\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.pern.pl\/en\/#website\",\"url\":\"https:\/\/www.pern.pl\/en\/\",\"name\":\"PERN\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.pern.pl\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IMG - Centrala PERN nap\u0119dzana energi\u0105 s\u0142oneczn\u0105 - PERN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/","og_locale":"en_US","og_type":"article","og_title":"IMG - Centrala PERN nap\u0119dzana energi\u0105 s\u0142oneczn\u0105 - PERN","og_url":"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/","og_site_name":"PERN","og_image":[{"width":1920,"height":640,"url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/","url":"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/","name":"IMG - Centrala PERN nap\u0119dzana energi\u0105 s\u0142oneczn\u0105 - PERN","isPartOf":{"@id":"https:\/\/www.pern.pl\/en\/#website"},"datePublished":"2022-09-05T11:20:47+00:00","breadcrumb":{"@id":"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.pern.pl\/en\/img-centrala-pern-napedzana-energia-sloneczna-17-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.pern.pl\/en\/"},{"@type":"ListItem","position":2,"name":"IMG &#8211; Centrala PERN nap\u0119dzana energi\u0105 s\u0142oneczn\u0105"}]},{"@type":"WebSite","@id":"https:\/\/www.pern.pl\/en\/#website","url":"https:\/\/www.pern.pl\/en\/","name":"PERN","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pern.pl\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"100\" src=\"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-300x100.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-300x100.jpg 300w, https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-1024x341.jpg 1024w, https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-768x256.jpg 768w, https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-1536x512.jpg 1536w, https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-1200x400.jpg 1200w, https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18.jpg 1920w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1920,"height":640,"file":"2022\/03\/3cc27628942ba53a6894aef65e41de64-18.jpg","filesize":403405,"sizes":{"medium":{"file":"3cc27628942ba53a6894aef65e41de64-18-300x100.jpg","width":300,"height":100,"filesize":8752,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-300x100.jpg"},"large":{"file":"3cc27628942ba53a6894aef65e41de64-18-1024x341.jpg","width":1024,"height":341,"filesize":76415,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-1024x341.jpg"},"thumbnail":{"file":"3cc27628942ba53a6894aef65e41de64-18-150x150.jpg","width":150,"height":150,"filesize":6752,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-150x150.jpg"},"medium_large":{"file":"3cc27628942ba53a6894aef65e41de64-18-768x256.jpg","width":768,"height":256,"filesize":44359,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-768x256.jpg"},"1536x1536":{"file":"3cc27628942ba53a6894aef65e41de64-18-1536x512.jpg","width":1536,"height":512,"filesize":156170,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-1536x512.jpg"},"post-thumbnail":{"file":"3cc27628942ba53a6894aef65e41de64-18-1200x400.jpg","width":1200,"height":400,"filesize":100500,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18-1200x400.jpg"},"full":{"file":"3cc27628942ba53a6894aef65e41de64-18.jpg","width":1920,"height":640,"mime_type":"image\/jpeg","source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.pern.pl\/wp-content\/uploads\/2022\/03\/3cc27628942ba53a6894aef65e41de64-18.jpg","_links":{"self":[{"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/media\/28469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/types\/attachment"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pern.pl\/en\/wp-json\/wp\/v2\/comments?post=28469"}]}}